{"id":1708,"date":"2019-09-10T16:58:15","date_gmt":"2019-09-10T16:58:15","guid":{"rendered":"http:\/\/bizkaiatletismo.eu\/eskola\/?p=1708"},"modified":"2019-09-10T16:58:15","modified_gmt":"2019-09-10T16:58:15","slug":"eskola-bilera-reunion-escolar-2","status":"publish","type":"post","link":"https:\/\/bizkaiatletismo.eu\/eskola\/2019\/09\/10\/eskola-bilera-reunion-escolar-2\/","title":{"rendered":"Eskola Bilera\/Reuni\u00f3n escolar"},"content":{"rendered":"\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" src=\"http:\/\/bizkaiatletismo.eu\/eskola\/wp-content\/uploads\/2013\/01\/EskolaKirolak.jpg\" alt=\"\" class=\"wp-image-15\" width=\"312\" height=\"112\" srcset=\"https:\/\/bizkaiatletismo.eu\/eskola\/wp-content\/uploads\/2013\/01\/EskolaKirolak.jpg 435w, https:\/\/bizkaiatletismo.eu\/eskola\/wp-content\/uploads\/2013\/01\/EskolaKirolak-300x107.jpg 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/><\/figure>\n\n\n\n<p>Irailaren 25ean eskola bilera ospatuko da 18.30etan kirol etxean (401 gela).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Irailaren 25ean eskola bilera ospatuko da 18.30etan kirol etxean (401 gela).<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/posts\/1708"}],"collection":[{"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/comments?post=1708"}],"version-history":[{"count":3,"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/posts\/1708\/revisions"}],"predecessor-version":[{"id":1711,"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/posts\/1708\/revisions\/1711"}],"wp:attachment":[{"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/media?parent=1708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/categories?post=1708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bizkaiatletismo.eu\/eskola\/wp-json\/wp\/v2\/tags?post=1708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}